{"id":14848,"date":"2023-12-05T17:54:10","date_gmt":"2023-12-05T17:54:10","guid":{"rendered":"https:\/\/bravenlyglobal.com\/wp-content\/uploads\/2023\/09\/Ignite.png"},"modified":"2023-12-05T17:54:10","modified_gmt":"2023-12-05T17:54:10","slug":"ignite-2-2","status":"inherit","type":"attachment","link":"\/es\/ignite-2-2\/","title":{"rendered":"Ignite"},"author":191432658,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":""},"class_list":["post-14848","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https://d1jeyrxw15fk4e.cloudfront.net/es/https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite-300x300.png 300w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite-150x150.png 150w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite-768x768.png 768w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite-480x480.png 480w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite.png 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":800,"height":800,"file":"2023\/09\/Ignite.png","filesize":20201,"sizes":{"medium":{"file":"Ignite-300x300.png","width":300,"height":300,"filesize":14236,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite-300x300.png"},"thumbnail":{"file":"Ignite-150x150.png","width":150,"height":150,"filesize":5224,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite-150x150.png"},"medium_large":{"file":"Ignite-768x768.png","width":768,"height":768,"filesize":60646,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite-768x768.png"},"et-pb-post-main-image":{"file":"Ignite-400x250.png","width":400,"height":250,"filesize":21002,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite-400x250.png"},"et-pb-post-main-image-fullwidth":{"file":"Ignite-800x675.png","width":800,"height":675,"filesize":65857,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite-800x675.png"},"et-pb-portfolio-image":{"file":"Ignite-400x284.png","width":400,"height":284,"filesize":21307,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite-400x284.png"},"et-pb-portfolio-module-image":{"file":"Ignite-510x382.png","width":510,"height":382,"filesize":31901,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite-510x382.png"},"et-pb-gallery-module-image-portrait":{"file":"Ignite-400x516.png","width":400,"height":516,"filesize":32334,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite-400x516.png"},"et-pb-image--responsive--phone":{"file":"Ignite-480x480.png","width":480,"height":480,"filesize":29324,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite-480x480.png"},"full":{"file":"Ignite.png","width":800,"height":800,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2023\/09\/Ignite.png","filename":"Ignite.png","filesize":20201,"_links":{"self":[{"href":"https:\/\/abbykissell.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/media\/14848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abbykissell.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/abbykissell.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/abbykissell.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/users\/191432658"}],"replies":[{"embeddable":true,"href":"https:\/\/abbykissell.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/comments?post=14848"}]}}